{"id":529,"date":"2016-12-27T18:57:11","date_gmt":"2016-12-27T17:57:11","guid":{"rendered":"http:\/\/entreprise.forum.com.tn\/?page_id=529"},"modified":"2017-04-27T17:02:17","modified_gmt":"2017-04-27T15:02:17","slug":"les-brochettes","status":"publish","type":"page","link":"http:\/\/www.forum.com.tn\/entreprise\/Fr\/banquets\/le-sale-fin\/les-brochettes\/","title":{"rendered":"LES BROCHETTES"},"content":{"rendered":"<div class=\"inner-detail-text container\">\r\n                          \r\n <div class=\"liste-fine-bouch\u00e9es\">\r\n  <ul>\r\n \t<li>Asiatika<\/li>\r\n<li> \t*** <\/li>\r\n        \r\n \t<li>Brochette asiatique filet de boeuf<\/li>\r\n<li> \t*** <\/li>\r\n<li>Brochette asiatique poulet<\/li>\r\n<li> \t*** <\/li>\r\n<li>Brochette crevettes zeste de citron<\/li>\r\n<li> \t*** <\/li>\r\n<li>Brochette poulet pruneaux<\/li>\r\n<li> \t*** <\/li>\r\n<li>Croisette<\/li>\r\n<li> \t*** <\/li>\r\n<li>Fricadelle<\/li>\r\n<li> \t*** <\/li>\r\n<li>Jardini\u00e8re au saumon<\/li>\r\n<li> \t*** <\/li>\r\n<li>Poignet br\u00e9saola parmesan<\/li>\r\n<li> \t*** <\/li>\r\n<li>Poulet \u00e0 l'orange<\/li>\r\n<li> \t*** <\/li>\r\n<li>Roulades de cr\u00eapes vari\u00e9es<\/li>\r\n<li> \t*** <\/li>\r\n<li>Seiches farcies aux crevettes<\/li>\r\n<li> \t*** <\/li>\r\n<li>Symphonie<\/li>\r\n<li> \t*** <\/li>\r\n\r\n   <\/ul>\r\n  <\/div>\r\n\r\n<div class=\"personnalisez-formule\">\r\n               \r\n            <\/div>\r\n<div class=\"tarif\">\r\n<span class=\"consulter\"> Tarif (nous consulter)<\/span>\r\n<\/div>\r\n\r\n\r\n <\/div>\r\n<div class=\"download-section\">\r\n        <div class=\"detail-icons\">\r\n\r\n              <div class=\"send-detail\" >\r\n                <a href=\"#myModal\"  data-toggle=\"modal\"> <span id=\"hidden-text\">abcd<\/span><\/a>\r\n            <\/div>\r\n\r\n            <div class=\"download-detail\">\r\n                <a href=\"http:\/\/entreprise.forum.com.tn\/wp-content\/uploads\/sites\/2\/2017\/03\/4-Les-Brochettes.pdf\" target=\"_blank\"> <span id=\"hidden-text\">abcd<\/span><\/a>\r\n            <\/div>\r\n\r\n            <div class=\"print-detail\">\r\n                <a href=\"http:\/\/entreprise.forum.com.tn\/wp-content\/uploads\/sites\/2\/2017\/03\/4-Les-Brochettes.pdf\" target=\"_blank\"> <span id=\"hidden-text\">abcd<\/span><\/a>\r\n            <\/div>\r\n\r\n        <\/div>\r\n    <\/div>","protected":false},"excerpt":{"rendered":"Asiatika *** Brochette asiatique filet de boeuf *** Brochette asiatique poulet *** Brochette crevettes zeste de citron *** Brochette poulet pruneaux *** Croisette *** Fricadelle *** Jardini\u00e8re au saumon *** Poignet br\u00e9saola parmesan *** Poulet \u00e0 l&rsquo;orange *** Roulades de cr\u00eapes vari\u00e9es *** Seiches farcies aux crevettes *** Symphonie *** Tarif (nous consulter) abcd abcd <a class=\"read-more\" href=\"http:\/\/www.forum.com.tn\/entreprise\/Fr\/banquets\/le-sale-fin\/les-brochettes\/\">&#8230;<\/a>","protected":false},"author":1,"featured_media":518,"parent":494,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"single-detail.php","meta":[],"_links":{"self":[{"href":"http:\/\/www.forum.com.tn\/entreprise\/Fr\/wp-json\/wp\/v2\/pages\/529"}],"collection":[{"href":"http:\/\/www.forum.com.tn\/entreprise\/Fr\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"http:\/\/www.forum.com.tn\/entreprise\/Fr\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"http:\/\/www.forum.com.tn\/entreprise\/Fr\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"http:\/\/www.forum.com.tn\/entreprise\/Fr\/wp-json\/wp\/v2\/comments?post=529"}],"version-history":[{"count":12,"href":"http:\/\/www.forum.com.tn\/entreprise\/Fr\/wp-json\/wp\/v2\/pages\/529\/revisions"}],"predecessor-version":[{"id":1852,"href":"http:\/\/www.forum.com.tn\/entreprise\/Fr\/wp-json\/wp\/v2\/pages\/529\/revisions\/1852"}],"up":[{"embeddable":true,"href":"http:\/\/www.forum.com.tn\/entreprise\/Fr\/wp-json\/wp\/v2\/pages\/494"}],"wp:featuredmedia":[{"embeddable":true,"href":"http:\/\/www.forum.com.tn\/entreprise\/Fr\/wp-json\/wp\/v2\/media\/518"}],"wp:attachment":[{"href":"http:\/\/www.forum.com.tn\/entreprise\/Fr\/wp-json\/wp\/v2\/media?parent=529"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}